{"id":2940,"date":"2021-12-03T14:47:22","date_gmt":"2021-12-03T13:47:22","guid":{"rendered":"https:\/\/chalettyrosolios.fr\/?page_id=2940"},"modified":"2025-06-03T12:00:17","modified_gmt":"2025-06-03T11:00:17","slug":"ete","status":"publish","type":"page","link":"https:\/\/chalettyrosolios.fr\/en\/ete\/","title":{"rendered":"Chalets Tyrosolios en \u00e9t\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2940\" class=\"elementor elementor-2940\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-312e18f elementor-section-stretched elementor-section-height-full elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"312e18f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;true&quot;,&quot;hoteller_ext_is_background_parallax_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a623eb\" data-id=\"4a623eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9586e2 elementor-widget elementor-widget-heading\" data-id=\"a9586e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;true&quot;,&quot;hoteller_ext_is_fadeout_animation_velocity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.4,&quot;sizes&quot;:[]},&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation_direction&quot;:&quot;up&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default translation-block\">Experience an exceptional stay<br>in our luxury chalet<br>in Meribel<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8b9b0e elementor-widget elementor-widget-text-editor\" data-id=\"e8b9b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;true&quot;,&quot;hoteller_ext_is_fadeout_animation_velocity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation_direction&quot;:&quot;up&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd077ac elementor-section-stretched all-images elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd077ac\" data-element_type=\"section\" data-e-type=\"section\" id=\"blue-image\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;true&quot;,&quot;hoteller_ext_background_on_scroll_color&quot;:&quot;#FFFFFF&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-cf9d71d\" data-id=\"cf9d71d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26a9351 elementor-widget elementor-widget-image\" data-id=\"26a9351\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-showme=\"blue-image\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-1024x683.jpg\" class=\"attachment-large size-large wp-image-2548\" alt=\"\" srcset=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-1024x683.jpg 1024w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-300x200.jpg 300w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-768x512.jpg 768w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-1536x1024.jpg 1536w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-2048x1366.jpg 2048w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-700x466.jpg 700w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/CONTENU_Tyrosolios_Terrasse_Jardin_Journ\u251ca\u252c\u00aee_Repos_Ete-440x293.jpg 440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e4e52dc\" data-id=\"e4e52dc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47b6bbe elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"47b6bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">COMFORT AND CONVIVIALITY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-605596e elementor-widget elementor-widget-heading\" data-id=\"605596e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Treat yourself to a slice of heaven in our luxury chalet <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ecb5fa elementor-widget elementor-widget-text-editor\" data-id=\"9ecb5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDo you need to reconnect with nature? Do you want to escape to the mountains or enjoy the pleasures of skiing in our world-class ski area? Then join us at Chalet Tyrosolios: your own luxury chalet for your next holiday<span style=\"font-family:'Times New Roman'\">&#8230;<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b202033 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b202033\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/chalettyrosolios.fr\/en\/nos-prestations\/\">Discover more<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb240f3 elementor-section-stretched all-images elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb240f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;true&quot;,&quot;hoteller_ext_background_on_scroll_color&quot;:&quot;#9D7D6B&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-6043e12\" data-id=\"6043e12\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e7fb3 elementor-widget elementor-widget-image\" data-id=\"36e7fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-showme=\"blue-image\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"600\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Luxueux-chalets.png\" class=\"attachment-large size-large wp-image-856\" alt=\"\" srcset=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Luxueux-chalets.png 833w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Luxueux-chalets-300x216.png 300w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Luxueux-chalets-768x553.png 768w, https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Luxueux-chalets-440x317.png 440w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4267242\" data-id=\"4267242\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e3444b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2e3444b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">COMFORT AND CONVIVIALITY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec11850 elementor-widget elementor-widget-hoteller-animated-text\" data-id=\"ec11850\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-bottom overflow-hidden\" data-delimiter=\"word\" data-transition=\"100\" data-transition-delay=\"100\" data-transition-duration=\"800\">\n\t\t<h2>\n\t\tTreat yourself to a slice of heaven in our luxury chalet \t<\/h2>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8cc57 elementor-widget elementor-widget-text-editor\" data-id=\"7f8cc57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDo you need to reconnect with nature? Do you want to escape to the mountains or enjoy the pleasures of skiing in our world-class ski area? Then join us at Chalet Tyrosolios: your own luxury chalet for your next holiday<span style=\"font-family:'Times New Roman'\">&#8230;<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bf20df elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6bf20df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/chalettyrosolios.fr\/en\/nos-prestations\/\">Discover more<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efd13cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efd13cd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b1d066\" data-id=\"5b1d066\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a6b8a7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8a6b8a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWe offer customized services for your vacation or business seminar. Tyrosolios will be your slice of heaven in the middle of beautiful mountains!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c4e48d elementor-widget elementor-widget-image\" data-id=\"3c4e48d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"51\" height=\"46\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/picto-soleil.svg\" class=\"attachment-full size-full wp-image-2692\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48612b4 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48612b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3623992\" data-id=\"3623992\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c4ef0 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"08c4ef0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">A PRESTIGIOUS CHALET<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e644b1 elementor-widget elementor-widget-heading\" data-id=\"3e644b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unforgettable moments with family or friends<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5393784\" data-id=\"5393784\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b49ae55 elementor-widget elementor-widget-text-editor\" data-id=\"b49ae55\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our luxury Savoyard chalet has a warm and authentic atmosphere. It is located in the middle of a world famous ski resort. You will find a convivial and cosy environment here, where you can enjoy the many services offered in this exceptional place.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db5dce5 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"db5dce5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca78cf6\" data-id=\"ca78cf6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7467a51 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-hoteller-service-carousel\" data-id=\"7467a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-service-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"1\" data-autoplay=\"0\" data-timer=\"6000\" data-items=\"3\" data-stage-padding=\"-80\" data-margin=\"15\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Chambres-de-reves-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">Dream suites <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">Dream suites with walk-in shower or bathtub and balcony to admire the breathtaking views<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2025\/06\/Tyro-Salon5-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A large living room  <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">Un grand salon avec un open bar, un coin jeux vid\u00e9o et flipper, un coin chemin\u00e9e et une biblioth\u00e8que.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/salle-a-manger--700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A dining room <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A dining room that can accommodate 25 people<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/cinema-1-700x466.png\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A movie room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A unique room with 22 seats for private screenings or shows<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2025\/06\/Kids-Play-Room-Tyrosolios-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A game room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">Un espace chaleureux et color\u00e9, pens\u00e9 pour l\u2019\u00e9veil et le plaisir des enfants, toboggan, biblioth\u00e8que, jouets. Un lieu id\u00e9al pour explorer, lire, jouer et grandir !\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/OLD-Tyrosolios_CaveVin-3.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A wine cellar<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A wine cellar where you can pick your own wines \u00e0 la carte<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/local-a-ski-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A ski room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A complete ski room where your equipment will be waiting for you if you want to enjoy the famous Meribel ski area.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/HD_transparent_picture-700x466.png\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5091d elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-hoteller-service-carousel\" data-id=\"2b5091d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-service-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"1\" data-autoplay=\"1\" data-timer=\"6000\" data-items=\"3\" data-stage-padding=\"25\" data-margin=\"30\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Chambres-de-reves-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">Dream suites <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">Dream suites with walk-in shower or bathtub and balcony to admire the breathtaking views<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Un-grand-salon-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A large living room  <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A large living room with an open bar, a reading room, a fireplace and a giant TV screen<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/salle-a-manger--700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A dining room <\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A dining room that can accommodate 25 people<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/cinema-1-700x466.png\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A movie room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A unique room with 22 seats for private screenings or shows<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/salle-de-jeux-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A game room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A game room for children<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/OLD-Tyrosolios_CaveVin-3.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A wine cellar<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A wine cellar where you can pick your own wines \u00e0 la carte<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/local-a-ski-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A ski room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">A complete ski room where your equipment will be waiting for you if you want to enjoy the famous Meribel ski area.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b32ca9 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b32ca9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;true&quot;,&quot;hoteller_ext_background_on_scroll_color&quot;:&quot;#C8B99E&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a65503c\" data-id=\"a65503c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20e1f60 elementor-widget elementor-widget-image\" data-id=\"20e1f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"76\" height=\"76\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/PLANTE-TYROSOLIOS-noir.svg\" class=\"attachment-large size-large wp-image-916\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8b307 elementor-widget elementor-widget-heading\" data-id=\"7f8b307\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">With its extraordinary facilities, Chalet Tyrosolios is a place of luxury, calm and pleasure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13165ac elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"13165ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/chalettyrosolios.fr\/en\/nos-suites\/\">Discover more<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa4c510 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aa4c510\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95e6cbe\" data-id=\"95e6cbe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5ad1a7 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-hoteller-service-carousel\" data-id=\"b5ad1a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-service-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"1\" data-autoplay=\"1\" data-timer=\"6000\" data-items=\"3\" data-stage-padding=\"25\" data-margin=\"30\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Nos-equipements-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A massage room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">with professional massage equipment, where you can relax in the hands of a professional masseur<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Hamam-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A swimming indoor spa<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">with balneo jets, rainy effect and a cosy atmosphere with an exceptional view on the mountain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Sauna-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A sauna and a hamman<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">for a relaxing aromatherapy experience<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Bucket-shower-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A bucket shower<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">the bucket shower guarantees a refreshing effect in the Tyrolean tradition<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc3304 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-hoteller-service-carousel\" data-id=\"1cc3304\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-service-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"1\" data-autoplay=\"0\" data-timer=\"6000\" data-items=\"3\" data-stage-padding=\"-80\" data-margin=\"15\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Nos-equipements-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A massage room<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">with professional massage equipment, where you can relax in the hands of a professional masseur<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Hamam-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A swimming indoor spa<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">with balneo jets, rainy effect and a cosy atmosphere with an exceptional view on the mountain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Sauna-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A sauna and a hamman<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">for a relaxing aromatherapy experience<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-image\">\n\t\t\t\t\t\t<div class=\"service-carousel-image-overflow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Bucket-shower-700x466.jpg\" alt=\"\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"service-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"service-carousel-title\">A bucket shower<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"service-carousel-desc\">the bucket shower guarantees a refreshing effect in the Tyrolean tradition<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fe7efc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fe7efc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4084877\" data-id=\"4084877\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-728782f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"728782f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\" style=\"text-align: center;\">A COMPANY TRIP<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abae8e1 elementor-widget elementor-widget-hoteller-animated-text\" data-id=\"abae8e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"word\" data-transition=\"100\" data-transition-delay=\"100\" data-transition-duration=\"800\">\n\t\t<h2>\n\t\tA luxury chalet in the mountains,<br>\nfor a successful company seminar\t<\/h2>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d25bbab elementor-widget elementor-widget-text-editor\" data-id=\"d25bbab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Do you want to strengthen team cohesion and communication? Our chalet allows you to organize professional events with our complete equipment and customized services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d093de6 elementor-widget elementor-widget-image\" data-id=\"d093de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/FLOCON-TYROSOLIOS.svg\" class=\"attachment-large size-large wp-image-965\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20b87dd elementor-widget elementor-widget-hoteller-service-grid\" data-id=\"20b87dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"service-grid-container\">\n<div class=\"service-grid-content-wrapper layout-tg_three_cols\" data-cols=\"3\" data-offset=\"-50%\">\n\t\t<div class=\"service-grid-wrapper tg_three_cols   service-1 tile scale-anm all smoove disable_none slide-up\" data-delay=\"150\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Suites-individuelles.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">Individual suites <\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tIndividual suites to maintain the privacy of each person\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"service-grid-wrapper tg_three_cols   service-2 tile scale-anm all smoove disable_none slide-up\" data-delay=\"300\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Service-de-restauration-gastronomique.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">Gourmet food service <\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tGastronomic restaurant service by our Chef \t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"service-grid-wrapper tg_three_cols last  service-3 tile scale-anm all smoove disable_none slide-up\" data-delay=\"450\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2025\/06\/Tyro-Salon13-1024x584.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">Convertible living room <\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tThe living room can be converted into a meeting room\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"service-grid-wrapper tg_three_cols   service-4 tile scale-anm all smoove disable_none slide-up\" data-delay=\"150\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Un-bureau-ferm\u251c\u00ae.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">A closed office<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tA closed office for your meetings \t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"service-grid-wrapper tg_three_cols   service-5 tile scale-anm all smoove disable_none slide-up\" data-delay=\"300\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/11\/TEAM-BULDING_Tyrosolios_Bureau_Salon_5-1-scaled-e1637771682762-928x1024.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">Team-building animations<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tWe can organize team-building activities for you, indoors or outdoors\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"service-grid-wrapper tg_three_cols last  service-6 tile scale-anm all smoove disable_none slide-up\" data-delay=\"450\" data-minwidth=\"1\" data-move-y=\"60px\" style=\"background-image: url('https:\/\/chalettyrosolios.fr\/wp-content\/uploads\/2021\/10\/Une-terrasse-de-250-m2.jpg');\">\n\t\t\t\t\t\t<div class=\"inner-wrap\">\n\t\t\t\t<div class=\"inner-wrap-border\">\n\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t<div class=\"header-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"service\">A 250 m2 terrace<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"hover-content\">\n\t\t\t\t\t\t\tThe 250 m2 terrace allows you to enjoy breathtaking views of La Saulire\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<br class=\"clear\"\/>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l&rsquo;envie de vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-2940","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies\" \/>\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/chalettyrosolios.fr\/en\/ete\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Chalet Tyrosolios - Chalets Du Hameau\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios\" \/>\n\t\t<meta property=\"og:description\" content=\"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chalettyrosolios.fr\/en\/ete\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-12-03T13:47:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-03T11:00:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/#listItem\",\"name\":\"Chalets Tyrosolios en \\u00e9t\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/#listItem\",\"position\":2,\"name\":\"Chalets Tyrosolios en \\u00e9t\\u00e9\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/#organization\",\"name\":\"Chalet Tyrosolios\",\"description\":\"Chalets Du Hameau\",\"url\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/#webpage\",\"url\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/\",\"name\":\"Chalets Tyrosolios en \\u00e9t\\u00e9 - Chalet Tyrosolios\",\"description\":\"Un s\\u00e9jour d\\u2019exception dans notre chalet de luxe \\u00e0 M\\u00e9ribel Louez un chalet de luxe situ\\u00e9 \\u00e0 M\\u00e9ribel, dans les Alpes Fran\\u00e7aises. CONFORT ET CONVIVIALIT\\u00c9 Offrez-vous une part de r\\u00eave dans notre luxueux chalet Si vous ressentez l\\u2019envie de vous reconnecter avec la nature, de vous \\u00e9vader \\u00e0 la montagne ou de profiter des joies\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/ete\\\/#breadcrumblist\"},\"datePublished\":\"2021-12-03T14:47:22+01:00\",\"dateModified\":\"2025-06-03T12:00:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/\",\"name\":\"Chalet Tyrosolios\",\"description\":\"Chalets Du Hameau\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/chalettyrosolios.fr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios","description":"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies","canonical_url":"https:\/\/chalettyrosolios.fr\/en\/ete\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/chalettyrosolios.fr\/en\/ete\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chalettyrosolios.fr\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/chalettyrosolios.fr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/chalettyrosolios.fr\/en\/ete\/#listItem","name":"Chalets Tyrosolios en \u00e9t\u00e9"}},{"@type":"ListItem","@id":"https:\/\/chalettyrosolios.fr\/en\/ete\/#listItem","position":2,"name":"Chalets Tyrosolios en \u00e9t\u00e9","previousItem":{"@type":"ListItem","@id":"https:\/\/chalettyrosolios.fr\/en#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/chalettyrosolios.fr\/en\/#organization","name":"Chalet Tyrosolios","description":"Chalets Du Hameau","url":"https:\/\/chalettyrosolios.fr\/en\/"},{"@type":"WebPage","@id":"https:\/\/chalettyrosolios.fr\/en\/ete\/#webpage","url":"https:\/\/chalettyrosolios.fr\/en\/ete\/","name":"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios","description":"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/chalettyrosolios.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/chalettyrosolios.fr\/en\/ete\/#breadcrumblist"},"datePublished":"2021-12-03T14:47:22+01:00","dateModified":"2025-06-03T12:00:17+01:00"},{"@type":"WebSite","@id":"https:\/\/chalettyrosolios.fr\/en\/#website","url":"https:\/\/chalettyrosolios.fr\/en\/","name":"Chalet Tyrosolios","description":"Chalets Du Hameau","inLanguage":"en-GB","publisher":{"@id":"https:\/\/chalettyrosolios.fr\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Chalet Tyrosolios - Chalets Du Hameau","og:type":"article","og:title":"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios","og:description":"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies","og:url":"https:\/\/chalettyrosolios.fr\/en\/ete\/","article:published_time":"2021-12-03T13:47:22+00:00","article:modified_time":"2025-06-03T11:00:17+00:00","twitter:card":"summary","twitter:title":"Chalets Tyrosolios en \u00e9t\u00e9 - Chalet Tyrosolios","twitter:description":"Un s\u00e9jour d\u2019exception dans notre chalet de luxe \u00e0 M\u00e9ribel Louez un chalet de luxe situ\u00e9 \u00e0 M\u00e9ribel, dans les Alpes Fran\u00e7aises. CONFORT ET CONVIVIALIT\u00c9 Offrez-vous une part de r\u00eave dans notre luxueux chalet Si vous ressentez l\u2019envie de vous reconnecter avec la nature, de vous \u00e9vader \u00e0 la montagne ou de profiter des joies"},"aioseo_meta_data":{"post_id":"2940","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":false,"robots_noindex":true,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-03 13:50:10","updated":"2025-06-04 10:35:13","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chalettyrosolios.fr\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tChalets Tyrosolios en \u00e9t\u00e9\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/chalettyrosolios.fr\/en"},{"label":"Chalets Tyrosolios en \u00e9t\u00e9","link":"https:\/\/chalettyrosolios.fr\/en\/ete\/"}],"_links":{"self":[{"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/pages\/2940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/comments?post=2940"}],"version-history":[{"count":0,"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/pages\/2940\/revisions"}],"wp:attachment":[{"href":"https:\/\/chalettyrosolios.fr\/en\/wp-json\/wp\/v2\/media?parent=2940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}